{"id":8509,"date":"2021-09-03T14:32:55","date_gmt":"2021-09-03T14:32:55","guid":{"rendered":"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/commander-des-tickets-restaurant\/"},"modified":"2021-09-03T14:32:55","modified_gmt":"2021-09-03T14:32:55","slug":"commander-des-tickets-restaurant","status":"publish","type":"content","link":"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/commander-des-tickets-restaurant\/","title":{"rendered":"Commander des tickets restaurant"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04993519dae\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04993519dae\" checked aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/commander-des-tickets-restaurant\/#Commander_des_tickets_restaurants\" >Commander des tickets restaurants<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/commander-des-tickets-restaurant\/#Vers_qui_dois-je_me_tourner_pour_commander_des_tickets_restaurant\" >Vers qui dois-je me tourner pour commander des tickets restaurant ?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/commander-des-tickets-restaurant\/#Edenred\" >Edenred<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/commander-des-tickets-restaurant\/#Sodexo\" >Sodexo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/commander-des-tickets-restaurant\/#Monizze\" >Monizze<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/commander-des-tickets-restaurant\/#Comment_proceder_pour_commander_des_tickets_restaurant\" >Comment proc\u00e9der pour commander des tickets restaurant ?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/commander-des-tickets-restaurant\/#Edenred-2\" >Edenred<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/commander-des-tickets-restaurant\/#Sodexo-2\" >Sodexo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/commander-des-tickets-restaurant\/#Monizze-2\" >Monizze<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/commander-des-tickets-restaurant\/#Commander_des_tickets_restaurant_Combien_ca_coute\" >Commander des tickets restaurant : Combien \u00e7a co\u00fbte ?<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Commander_des_tickets_restaurants\"><\/span>Commander des tickets restaurants<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Vous \u00eates d\u00e9cid\u00e9s \u00e0 investir dans les <a href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/\">tickets restaurant<\/a> mais vous ne savez pas vers qui vous tourner pour passer commande&nbsp;? Retrouvez ici l\u2019ensemble des conseils pratiques pour commander vos tickets restaurant et ainsi faire plaisir \u00e0 vos employ\u00e9s gr\u00e2ce \u00e0 cette <strong>augmentation de leur pouvoir d\u2019achat<\/strong>.<\/p>\n<div class=\"row\">\n<div style=\"text-align: center;\" class=\"col-md-12\">\n<p>&nbsp;<\/p>\n<p><a class=\"btn-base-bg-slide btn-slide btn-slide-right btn-base-md radius-3 bg-b2c active\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/#ppp\">Comparateur de Prix en Ligne !<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<h2><span class=\"ez-toc-section\" id=\"Vers_qui_dois-je_me_tourner_pour_commander_des_tickets_restaurant\"><\/span>Vers qui dois-je me tourner pour commander des tickets restaurant ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img decoding=\"async\" class=\"rounded mx-auto d-block\" alt=\"Ticket restaurant : quelle soci\u00e9t\u00e9 ?\" src=\"https:\/\/www.bobex.be\/shared\/be_fr_questionnement.png.png\" width=\"40%\" \/><\/p>\n<p>Le territoire belge est occup\u00e9 par <strong>trois soci\u00e9t\u00e9s<\/strong> qui se partagent le march\u00e9&nbsp;: Edenred, Sodexo et Monizze. Il est donc possible de se diriger vers l\u2019une de ces trois soci\u00e9t\u00e9s pour acqu\u00e9rir des tickets restaurants. Nous allons vous pr\u00e9senter les avantages que celles-ci peuvent apporter \u00e0 votre soci\u00e9t\u00e9.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Edenred\"><\/span>Edenred<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>La soci\u00e9t\u00e9 propose une r\u00e9duction de 20% sur le tarif de base pour toute inscription en ligne<\/li>\n<li>Fiche d\u2019information et son mode d\u2019emploi<\/li>\n<li>Application mobile<\/li>\n<li>Espace Client (pour entreprise)<\/li>\n<li>Notifications par e-mail<\/li>\n<li>Centre d\u2019aide en ligne<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Sodexo\"><\/span>Sodexo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>9 choix d\u2019avantages : lunch, activit\u00e9, \u00e9co, \u2026<\/li>\n<li>Carte \u00e9lectronique ou ch\u00e8que papier<\/li>\n<li>Paiement s\u00e9curis\u00e9<\/li>\n<li>Code PIN<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Monizze\"><\/span>Monizze<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Un service r\u00e9actif<\/li>\n<li>Un rapport qualit\u00e9-prix<\/li>\n<li>Simple, rapide et s\u00e9curis\u00e9<\/li>\n<li>Une carte 3 en 1<\/li>\n<li><a href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/ou-utiliser-les-tickets-restaurant\/\">Un grand r\u00e9seau d\u2019acceptation<\/a><\/li>\n<\/ul>\n<div class=\"row\">\n<div style=\"text-align: center;\" class=\"col-md-12\">\n<p>&nbsp;<\/p>\n<p><a class=\"btn-base-bg-slide btn-slide btn-slide-right btn-base-md radius-3 bg-b2c active\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/#ppp\">Comparer les Offres en 2 Minutes !<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<h2><span class=\"ez-toc-section\" id=\"Comment_proceder_pour_commander_des_tickets_restaurant\"><\/span>Comment proc\u00e9der pour commander des tickets restaurant ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Vous avez pris la d\u00e9cision de commander des tickets restaurant pour vos employ\u00e9s mais c\u2019est un calvaire de trouver <strong>le bon fournisseur<\/strong> ? Nous avons s\u00e9lectionn\u00e9 les <strong>3 fournisseurs belges de titres-repas<\/strong> et avons comparons leurs diff\u00e9rentes d\u00e9marches dans l\u2019acquisition de ch\u00e8ques restaurants.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Edenred-2\"><\/span>Edenred<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Edenred propose sur son site web un document expliquant touche la d\u00e9marche manuelle \u00e0 effectuer pour se munir de ch\u00e8ques-repas dans son entreprise. <br \/>Vous devez juste pour laisser guider et suivre toutes les informations clairement expliqu\u00e9es vous permettant de r\u00e9aliser, par vous-m\u00eame, la commande des tickets-restaurants.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Sodexo-2\"><\/span>Sodexo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Sodexo mise eux sur le contact humain via t\u00e9l\u00e9phone pour commander des tickets-restaurant. Il est \u00e9galement possible de faire la d\u00e9marche sur leurs sites web si vous \u00eates muni de votre num\u00e9ro de TVA, cependant, la d\u00e9marche s\u2019arr\u00eatera l\u00e0 et un suivi mailing sera effectu\u00e9e par ceux-ci.&nbsp;<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Monizze-2\"><\/span>Monizze<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Monizze mise \u00e9galement sur leur plateforme web pour commander des tickets-restaurant comme le fait Edenred. Cependant il propose un double service \u00e0 savoir un enregistrement dit \u00ab manuel \u00bb ou un enregistrement via une commande standardis\u00e9 sur Excel.<br \/> Si vous ne vous y retrouvez toujours pas, Monizze vous propose une vid\u00e9o explicative qui simplifie l\u2019acc\u00e8s.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Commander_des_tickets_restaurant_Combien_ca_coute\"><\/span>Commander des tickets restaurant : Combien \u00e7a co\u00fbte ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img decoding=\"async\" class=\"rounded mx-auto d-block\" alt=\"Ticket restaurant : co\u00fbt\" src=\"https:\/\/www.bobex.be\/shared\/befr_tirelire.png\" \/><\/p>\n<p>Les ch\u00e8ques-repas ont des avantages fiscaux comme vous le savez d\u00e9j\u00e0, mais vous vous demandez combien co\u00fbte le service en lui-m\u00eame et donc chez qui vous tournez afin de <strong>b\u00e9n\u00e9ficier du meilleur service qualit\u00e9-prix<\/strong> ! Il faut en effet compter les frais de fonctionnement et de gestion de la carte \u00e9lectronique ou des ch\u00e8ques papiers pour conna\u00eetre le montant exacte que co\u00fbteront les tickets restaurants. Le co\u00fbt se situe <strong>sous les 100\u20ac\/an pour ce service tout compris<\/strong>.<\/p>\n<div class=\"row\">\n<div style=\"text-align: center;\" class=\"col-md-12\">\n<p>&nbsp;<\/p>\n<p><a class=\"btn-base-bg-slide btn-slide btn-slide-right btn-base-md radius-3 bg-b2c active\" href=\"https:\/\/www.bobex.lu\/fr-lu\/cheques-repas\/#ppp\">\u00c9conomisez en Comparant !<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"business":"7558","footnotes":""},"class_list":["post-8509","content","type-content","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.bobex.lu\/fr-lu\/wp-json\/wp\/v2\/content\/8509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bobex.lu\/fr-lu\/wp-json\/wp\/v2\/content"}],"about":[{"href":"https:\/\/www.bobex.lu\/fr-lu\/wp-json\/wp\/v2\/types\/content"}],"version-history":[{"count":0,"href":"https:\/\/www.bobex.lu\/fr-lu\/wp-json\/wp\/v2\/content\/8509\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bobex.lu\/fr-lu\/wp-json\/wp\/v2\/media?parent=8509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}